{"id":11502,"date":"2024-06-06T11:17:24","date_gmt":"2024-06-06T09:17:24","guid":{"rendered":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/?p=11502"},"modified":"2024-06-06T12:20:33","modified_gmt":"2024-06-06T10:20:33","slug":"jetzt-fuer-den-jugend-landtag-2024-bewerben","status":"publish","type":"post","link":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/2024\/06\/06\/jetzt-fuer-den-jugend-landtag-2024-bewerben\/","title":{"rendered":"Jetzt f\u00fcr den Jugend-Landtag 2024 bewerben!"},"content":{"rendered":"<p><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/2023\/07\/banner-landtag-2023.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-10453\" src=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/2023\/07\/banner-landtag-2023.jpg\" alt=\"\" width=\"700\" height=\"248\" srcset=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/2023\/07\/banner-landtag-2023.jpg 700w, https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/2023\/07\/banner-landtag-2023-300x106.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a>Die SPD-Abgeordneten Sonja Bongers, Frederick Cordes und Stefan Zimkeit laden drei Jugendliche dazu ein, vom 07. bis 09. November 2024 ihre Pl\u00e4tze im Parlament einzunehmen. An diesem Wochenende soll in D\u00fcsseldorf der dreit\u00e4gige Jugend-Landtag stattfinden.<\/p>\n<p>Diskutiert werden in unterschiedlichen Sitzungen aktuelle Themen, um die parlamentarischen Abl\u00e4ufe realit\u00e4tsnah zu simulieren. &#8222;Das ist eine tolle M\u00f6glichkeit, Demokratie hautnah zu erleben&#8220;, sagt Sonja Bongers. Und Frederick Cordes meint: &#8222;Unsere Demokratie lebt von jungen Menschen, die engagiert f\u00fcr ihre Positionen einstehen und Lust haben, sich f\u00fcr die Zukunft in NRW einzusetzen.&#8220;<!--more--><\/p>\n<p>195 junge Menschen werden in die Rolle eines Parlamentsmitglieds schl\u00fcpfen und Aussch\u00fcsse, Fraktionssitzung sowie Plenarberatung aktiv gestalten und den parlamentarischen Arbeitsalltag kennenlernen. &#8222;In den letzten Jahren wurde zum Beispiel \u00fcber die Themen \u201aPolitische Bildung f\u00f6rdern\u2018 oder wie man Ausbildungsberufe attraktiver machen und Fachkr\u00e4ftemangel in NRW l\u00f6sen kann, debattiert&#8220;, erinnert sich Stefan Zimkeit. Die Beschl\u00fcsse der &#8222;Jugend-Landtagsabgeordneten&#8220; werden anschlie\u00dfend den Abgeordneten des &#8222;wirklichen&#8220; Landtags vorgelegt.<\/p>\n<p>Ab sofort k\u00f6nnen sich junge Menschen aus Oberhausen, im Alter zwischen 16 und 20 Jahren, bewerben, indem sie sich bis Montag, 05. August 2024, unter <a href=\"mailto:sonja.bongers@landtag.nrw.de\">sonja.bongers@landtag.nrw.de<\/a> melden.<\/p>\n<p>Bewerbungen m\u00fcssen Telefonnummer, Adresse, Geburtsdatum, Geschlechtsidentit\u00e4t, eine Angabe, ob man zur Schule geht, studiert, in Ausbildung oder berufst\u00e4tig ist, sowie einen kurzen Satz enthalten, warum man beim Jugend-Landtag mitmachen m\u00f6chte. S\u00e4mtliche Kosten inklusive \u00dcbernachtung werden vom Landtag \u00fcbernommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die SPD-Abgeordneten Sonja Bongers, Frederick Cordes und Stefan Zimkeit laden drei Jugendliche dazu ein, vom 07. bis 09. November 2024 ihre Pl\u00e4tze im Parlament einzunehmen. An diesem Wochenende soll in&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[216],"tags":[796,4096,219],"quellen":[2806,1317,331],"class_list":["post-11502","post","type-post","status-publish","format-standard","hentry","category-land","tag-jugendlandtag","tag-jugendlandtag-2024","tag-landtag-nrw","quellen-mdl-frederick-cordes","quellen-mdl-sonja-bongers","quellen-mdl-stefan-zimkeit"],"_links":{"self":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts\/11502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/comments?post=11502"}],"version-history":[{"count":0,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts\/11502\/revisions"}],"wp:attachment":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/media?parent=11502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/categories?post=11502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/tags?post=11502"},{"taxonomy":"quellen","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/quellen?post=11502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}