{"id":13584,"date":"2026-05-09T12:53:07","date_gmt":"2026-05-09T10:53:07","guid":{"rendered":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/?p=13584"},"modified":"2026-05-10T10:19:55","modified_gmt":"2026-05-10T08:19:55","slug":"test-ub-parteitag","status":"publish","type":"post","link":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/2026\/05\/09\/test-ub-parteitag\/","title":{"rendered":"SPD Oberhausen w\u00e4hlt neue F\u00fchrung und bereitet Landtagswahl vor"},"content":{"rendered":"<p><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/2026\/05\/banner-klein-spd-oberhausen-ub-parteitag-26-05-11.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13611\" src=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/2026\/05\/banner-klein-spd-oberhausen-ub-parteitag-26-05-11.jpg\" alt=\"\" width=\"700\" height=\"250\" srcset=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/2026\/05\/banner-klein-spd-oberhausen-ub-parteitag-26-05-11.jpg 700w, https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/2026\/05\/banner-klein-spd-oberhausen-ub-parteitag-26-05-11-300x107.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a>Die Oberhausener SPD f\u00fchrt am <strong>Montag, 11.05.2026, ab 17.00 Uhr,<\/strong> im <strong>Casino-Saal von Haus Union<\/strong>, ihren Unterbezirksparteitag (Jahreshauptversammlung) mit der Neuwahl der gesamten F\u00fchrungsspitze durch. Im Anschluss beginnt <strong>gegen 20.00 Uhr<\/strong> die <strong>Vertreterversammlung<\/strong> zur Wahl der Delegierten und Ersatzdelegierten zur Landesdelegiertenkonferenz der NRWSPD, welche am 13.06.2026 die Landesreserveliste der SPD f\u00fcr die Landtagswahl am 25. April 2027 aufstellen wird. Abschlie\u00dfend findet <strong>ab ca. 20.30 Uhr<\/strong> die <strong>Wahlkreisdelegiertenkonferenz<\/strong> zur Aufstellung der SPD-Landtagskandidatin oder des SPD-Landtagskandiaten f\u00fcr den Wahlkreis 056-Oberhausen I (Alt-Oberhausen und Osterfeld) statt.<\/p>\n<p>Schwerpunkt des Parteitages ist die Neuwahl des Vorstandes der Oberhausener SPD. Daneben werden die 110 Delegierten \u00fcber <a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/2026\/05\/09\/test-ub-parteitag\/#spd-ob-ub-pt-antraege\">sieben Antr\u00e4ge<\/a> aus den Untergliederungen diskutieren und entscheiden.<!--more--><\/p>\n<div class=\"spd-ob-agenda\">\n<h4>UB-Parteitag<br \/>\nMO\u00a0\u00a0|\u00a0\u00a011.05.2026\u00a0\u00a0|\u00a0\u00a017.00 Uhr<\/h4>\n<h3>Vorl\u00e4ufige Tagesordnung<\/h3>\n<ol>\n<li>Er\u00f6ffnung des UB-Parteitages<\/li>\n<li>Begr\u00fc\u00dfung und Totenehrung<\/li>\n<li>Konstituierung:\n<ol type=\"a\">\n<li>Annahme einer Tagesordnung<\/li>\n<li>Annahme einer Gesch\u00e4ftsordnung<\/li>\n<li>Wahl einer Versammlungsleitung<\/li>\n<li>Wahl einer Mandatspr\u00fcfungskommission<\/li>\n<li>Wahl einer Z\u00e4hlkommission<\/li>\n<li>Wahl einer Antragskommission<\/li>\n<\/ol>\n<\/li>\n<li>Genehmigung der Niederschrift des Unterbezirksparteitages am 30.06.2025<\/li>\n<li>\n<ol type=\"a\">\n<li>\n<div class=\"spd-ob-main-item\"><strong class=\"spd-ob-uppercase\">Gru\u00dfwort von:<\/strong><br \/>\n<strong>Thorsten Berg<\/strong><br \/>\n<em>Oberb\u00fcrgermeister der Stadt Oberhausen<\/em><\/div>\n<\/li>\n<li>\n<div class=\"spd-ob-main-item\"><strong class=\"spd-ob-uppercase\">Gru\u00dfwort von:<\/strong><br \/>\n<strong>Manuel Prohl<\/strong><br \/>\n<em>Vorsitzender der SPD-Ratsfraktion Oberhausen<\/em><\/div>\n<\/li>\n<\/ol>\n<\/li>\n<li>Bericht der Mandatspr\u00fcfungskommission<\/li>\n<li>\n<ol type=\"a\">\n<li>\n<div class=\"spd-ob-main-item\"><strong class=\"spd-ob-uppercase\">Politischer und Organisationsbericht:<\/strong><br \/>\n<strong>Dirk V\u00f6pel MdB<\/strong><br \/>\n<em>UB-Vorsitzender<\/em><\/div>\n<\/li>\n<li>\n<div class=\"spd-ob-main-item\"><strong class=\"spd-ob-uppercase\">Kassenbericht:<\/strong><br \/>\n<strong>Nagihan Erdas<\/strong><br \/>\n<em>Schatzmeisterin<\/em><\/div>\n<\/li>\n<\/ol>\n<\/li>\n<li>Aussprache<\/li>\n<li>Bericht der Revisoren<\/li>\n<li>Entlastung des Vorstandes<\/li>\n<li><strong>Wahlen:<\/strong>\n<ol type=\"a\">\n<li>Wahl der <strong>Vorsitzenden<\/strong> oder des <strong>Vorsitzenden<\/strong><\/li>\n<li>Wahl der <strong>beiden Stellvertreterinnen<\/strong> oder <strong>Stellvertreter<\/strong><\/li>\n<li>Wahl der <strong>Schatzmeisterin<\/strong> oder des <strong>Schatzmeisters<\/strong><\/li>\n<li>Festlegung der <strong>Anzahl der weiteren Vorstandsmitglieder<\/strong><\/li>\n<li>Wahl von weiteren <strong>Vorstandsmitgliedern<\/strong><\/li>\n<li>Wahl von <strong>drei Revisorinnen<\/strong> oder <strong>Revisoren<\/strong><\/li>\n<li>Wahl einer <strong>Schiedskommission<\/strong><br \/>\n&#8211; Wahl der Vorsitzenden oder des Vorsitzenden<br \/>\n&#8211; Wahl der beiden Stellvertreterinnen oder Stellvertreter<br \/>\n&#8211; Wahl von vier Beisitzerinnen oder Beisitzern<\/li>\n<li>Wahl von zwei Delegierten und Ersatzdelegierten zum <strong>Bundesparteitag<\/strong><\/li>\n<li>Wahl von zwei Delegierten und Ersatzdelegierten f\u00fcr den <strong>Landesparteirat<\/strong><\/li>\n<li>Wahl von sechs Delegierten und Ersatzdelegierten zum <strong>Landesparteitag<\/strong><\/li>\n<li>Wahl von f\u00fcnf Delegierten und Ersatzdelegierten zu den <strong>Regionalkonferenzen<\/strong><\/li>\n<li>Wahl von voraussichtlich drei Delegierten und Ersatzdelegierten zu den <strong>Ruhrparteitagen<\/strong><\/li>\n<li>Wahl von einem Delegierten und Ersatzdelegierten f\u00fcr den <strong>Regionalausschuss<\/strong><\/li>\n<\/ol>\n<\/li>\n<li>Beratung der <strong>Antr\u00e4ge:<\/strong><br \/>\nBeratung von <a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/2026\/05\/09\/test-ub-parteitag\/#spd-ob-ub-pt-antraege\">Antr\u00e4gen<\/a>, soweit sie nicht unter den bisherigen Punkten 1 bis 11 bereits behandelt worden sind.<\/li>\n<li>Abschluss des Unterbezirksparteitages<\/li>\n<\/ol>\n<\/div>\n<div class=\"spd-ob-agenda\">\n<h4>Unterbezirks-Delegiertenkonferenz<br \/>\n<span style=\"font-weight: 400; font-style: italic;\">zur Landtagswahl am 25.04.2027<\/span><br \/>\nMO\u00a0\u00a0|\u00a0\u00a011.05.2026\u00a0\u00a0|\u00a0\u00a020.00 Uhr<\/h4>\n<h3>Vorl\u00e4ufige Tagesordnung<\/h3>\n<ol>\n<li>Er\u00f6ffnung der Unterbezirks-Delegiertenkonferenz<\/li>\n<li>Konstituierung:\n<ol type=\"a\">\n<li>Annahme einer Tagesordnung<\/li>\n<li>Annahme einer Gesch\u00e4ftsordnung<\/li>\n<li>Wahl einer Versammlungsleitung<\/li>\n<li>Wahl einer Mandatspr\u00fcfungskommission<\/li>\n<li>Wahl einer Z\u00e4hlkommission<\/li>\n<\/ol>\n<\/li>\n<li>Bericht der Mandatspr\u00fcfungskommission<\/li>\n<li><strong>Wahl der drei Delegierten und Ersatzdelegierten zur Landes-Delegierten\u00adkonferenz<\/strong> am 13.06.2026 zur Aufstellung der Landesliste der NRWSPD f\u00fcr die Landtagswahl 2027<\/li>\n<li>Abschluss der Unterbezirks-Delegiertenkonferenz<\/li>\n<\/ol>\n<\/div>\n<div class=\"spd-ob-agenda\">\n<h4>Wahlkreis-Delegiertenkonferenz<br \/>\n<span style=\"font-weight: 400; font-style: italic;\">zur Landtagswahl am 25.04.2027<\/span><br \/>\nMO\u00a0\u00a0|\u00a0\u00a011.05.2026\u00a0\u00a0|\u00a0\u00a020.30 Uhr<\/h4>\n<h3>Vorl\u00e4ufige Tagesordnung<\/h3>\n<ol>\n<li>Er\u00f6ffnung der Wahlkreis-Delegiertenkonferenz<\/li>\n<li>Konstituierung:\n<ol type=\"a\">\n<li>Annahme einer Tagesordnung<\/li>\n<li>Annahme einer Gesch\u00e4ftsordnung<\/li>\n<li>Wahl einer Versammlungsleiterin \/ eines Versammlungsleiters<\/li>\n<li>Wahl einer Schriftf\u00fchrerein \/ eines Schriftf\u00fchrers<\/li>\n<li>Wahl einer Mandatspr\u00fcfungskommission<\/li>\n<li>Wahl einer Wahlkommission<\/li>\n<\/ol>\n<\/li>\n<li>Bericht der Mandatspr\u00fcfungskommission<\/li>\n<li>Best\u00e4tigung der Formalit\u00e4ten gem\u00e4\u00df den Bestimmungen des Landeswahlgesetzes<\/li>\n<li>Wahl einer Vertrauensperson und einer stellvertretenden Vertrauensperson f\u00fcr den Wahlvorschlag<\/li>\n<li>Wahl von zwei Personen zur Abgabe der eidesstattlichen Versicherung<\/li>\n<li><strong>Wahlen:<\/strong><br \/>\n<strong>Wahl der Kandidatin bzw. des Kandidaten zur Kandidatur im Landtagswahlkreis 056 &#8211; Oberhausen I<\/strong> (kreisfreie Stadt Oberhausen, Stadtbezirke Alt-Oberhausen und Osterfeld)<\/li>\n<li>Beschluss der Niederschrift<\/li>\n<li>Abschluss der Wahlkreis-Delegiertenkonferenz<\/li>\n<\/ol>\n<\/div>\n<h3 id=\"spd-ob-ub-pt-antraege\" class=\"spd-ob-crossheading\">Antr\u00e4ge zum UB-Parteitag am 11.05.2026:<\/h3>\n<div class=\"spd-ob-ub-pt-at\">\n<div class=\"spd-ob-ub-pt-at-item\">\n<h3 class=\"spd-ob-ub-pt-at-subheadline\">Antrag Nr. 3:<\/h3>\n<h2 class=\"spd-ob-ub-pt-at-headline\"><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/antraege-ub-parteitag\/ub-pt-26-05-11-at-03-sondernutzung-gastronomiebetriebe.pdf\" title=\"Download pdf-Datei\" target=\"_blank\" rel=\"noopener\">Verzicht auf Geb\u00fchrenerhebung bei genehmigungsf\u00e4higen Gastronomiebereichen auf \u00f6ffentlichen Pl\u00e4tzen und B\u00fcrgersteigen <i class=\"fa-solid fa-file-pdf\"><\/i><\/a><\/h2>\n<div class=\"spd-ob-ub-pt-at-applicant\"><span class=\"spd-ob-ub-pt-at-applicant-title\">Antragsteller:<\/span><br \/>AG 60 plus<\/div>\n<div class=\"spd-ob-ub-pt-at-addressee\"><span class=\"spd-ob-ub-pt-at-addressee-title\">Adressat:<\/span><br \/>SPD-Unterbezirks-Parteitag<\/div>\n<\/div>\n<div class=\"spd-ob-ub-pt-at-item\">\n<h3 class=\"spd-ob-ub-pt-at-subheadline\">Antrag Nr. 5:<\/h3>\n<h2 class=\"spd-ob-ub-pt-at-headline\"><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/antraege-ub-parteitag\/ub-pt-26-05-11-at-05-teil-sondervermoegen-fuer-barrierefreiheit.pdf\" title=\"Download pdf-Datei\" target=\"_blank\" rel=\"noopener\">Teil des Sonderverm\u00f6gens f\u00fcr die Schaffung und den Erhalt von Barrierefreiheit verwenden <i class=\"fa-solid fa-file-pdf\"><\/i><\/a><\/h2>\n<div class=\"spd-ob-ub-pt-at-applicant\"><span class=\"spd-ob-ub-pt-at-applicant-title\">Antragsteller:<\/span><br \/>AG &#8222;SelbstAktiv&#8220;<\/div>\n<div class=\"spd-ob-ub-pt-at-addressee\"><span class=\"spd-ob-ub-pt-at-addressee-title\">Adressat:<\/span><br \/>SPD-Unterbezirksparteitag<\/div>\n<\/div>\n<div class=\"spd-ob-ub-pt-at-item\">\n<h3 class=\"spd-ob-ub-pt-at-subheadline\">Antrag Nr. 6:<\/h3>\n<h2 class=\"spd-ob-ub-pt-at-headline\"><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/antraege-ub-parteitag\/ub-pt-26-05-11-at-06-barrierefreiheit-bei-spd-veranstaltungen-ausweisen.pdf\" title=\"Download pdf-Datei\" target=\"_blank\" rel=\"noopener\">Barrierefreiheit bei SPD-Veranstaltungen <i class=\"fa-solid fa-file-pdf\"><\/i><\/a><\/h2>\n<div class=\"spd-ob-ub-pt-at-applicant\"><span class=\"spd-ob-ub-pt-at-applicant-title\">Antragsteller:<\/span><br \/>AG &#8222;SelbstAktiv&#8220;<\/div>\n<div class=\"spd-ob-ub-pt-at-addressee\"><span class=\"spd-ob-ub-pt-at-addressee-title\">Adressat:<\/span><br \/>SPD-Unterbezirksparteitag<\/div>\n<\/div>\n<div class=\"spd-ob-ub-pt-at-item\">\n<h3 class=\"spd-ob-ub-pt-at-subheadline\">Antrag Nr. 8:<\/h3>\n<h2 class=\"spd-ob-ub-pt-at-headline\"><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/antraege-ub-parteitag\/ub-pt-26-05-11-at-08-boellerverbotszone.pdf\" title=\"Download pdf-Datei\" target=\"_blank\" rel=\"noopener\">Stadtweites Verbot von privatem Feuerwerk zum Jahreswechsel <i class=\"fa-solid fa-file-pdf\"><\/i><\/a><\/h2>\n<div class=\"spd-ob-ub-pt-at-applicant\"><span class=\"spd-ob-ub-pt-at-applicant-title\">Antragsteller:<\/span><br \/>Jungsozialisten<\/div>\n<div class=\"spd-ob-ub-pt-at-addressee\"><span class=\"spd-ob-ub-pt-at-addressee-title\">Adressat:<\/span><br \/>SPD-Unterbezirksparteitag,<br \/>SPD-Ratsfraktion<\/div>\n<\/div>\n<div class=\"spd-ob-ub-pt-at-item\">\n<h3 class=\"spd-ob-ub-pt-at-subheadline\">Antrag Nr. 9:<\/h3>\n<h2 class=\"spd-ob-ub-pt-at-headline\"><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/antraege-ub-parteitag\/ub-pt-26-05-11-at-09-gluecksspiel.pdf\" title=\"Download pdf-Datei\" target=\"_blank\" rel=\"noopener\">Wenn Gl\u00fccksspiel zum Alltag wird, verlieren Kinder und Jugendliche ihren Schutz! <i class=\"fa-solid fa-file-pdf\"><\/i><\/a><\/h2>\n<div class=\"spd-ob-ub-pt-at-applicant\"><span class=\"spd-ob-ub-pt-at-applicant-title\">Antragsteller:<\/span><br \/>Jungsozialisten<\/div>\n<div class=\"spd-ob-ub-pt-at-addressee\"><span class=\"spd-ob-ub-pt-at-addressee-title\">Adressat:<\/span><br \/>SPD-Unterbezirksparteitag<\/div>\n<\/div>\n<div class=\"spd-ob-ub-pt-at-item\">\n<h3 class=\"spd-ob-ub-pt-at-subheadline\">Antrag Nr. 12:<\/h3>\n<h2 class=\"spd-ob-ub-pt-at-headline\"><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/antraege-ub-parteitag\/ub-pt-26-05-11-at-12-entsiegelung.pdf\" title=\"Download pdf-Datei\" target=\"_blank\" rel=\"noopener\">Entsiegelung und Begr\u00fcnung als festen Bestandteil der Stadtentwicklung in Oberhausen verankern <i class=\"fa-solid fa-file-pdf\"><\/i><\/a><\/h2>\n<div class=\"spd-ob-ub-pt-at-applicant\"><span class=\"spd-ob-ub-pt-at-applicant-title\">Antragsteller:<\/span><br \/>Jungsozialisten<\/div>\n<div class=\"spd-ob-ub-pt-at-addressee\"><span class=\"spd-ob-ub-pt-at-addressee-title\">Adressat:<\/span><br \/>SPD-Unterbezirksparteitag,<br \/>SPD-Ratsfraktion<\/div>\n<\/div>\n<div class=\"spd-ob-ub-pt-at-item\">\n<h3 class=\"spd-ob-ub-pt-at-subheadline\">Antrag Nr. 16:<\/h3>\n<h2 class=\"spd-ob-ub-pt-at-headline\"><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/antraege-ub-parteitag\/ub-pt-26-05-11-at-16-nachhaltige-staerkung-und-absicherung-oberhausener-frauenhaus.pdf\" title=\"Download pdf-Datei\" target=\"_blank\" rel=\"noopener\">Oberhausener Frauenhaus dauerhaft finanziell, strukturell und personell st\u00e4rken <i class=\"fa-solid fa-file-pdf\"><\/i><\/a><\/h2>\n<div class=\"spd-ob-ub-pt-at-applicant\"><span class=\"spd-ob-ub-pt-at-applicant-title\">Antragsteller:<\/span><br \/>Jungsozialisten<\/div>\n<div class=\"spd-ob-ub-pt-at-addressee\"><span class=\"spd-ob-ub-pt-at-addressee-title\">Adressat:<\/span><br \/>SPD-Unterbezirksparteitag<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Oberhausener SPD f\u00fchrt am Montag, 11.05.2026, ab 17.00 Uhr, im Casino-Saal von Haus Union, ihren Unterbezirksparteitag (Jahreshauptversammlung) mit der Neuwahl der gesamten F\u00fchrungsspitze durch. Im Anschluss beginnt gegen 20.00&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173,171],"tags":[4758,959,73,4816,4817,789],"quellen":[327],"class_list":["post-13584","post","type-post","status-publish","format-standard","hentry","category-parteileben","category-veranstaltungen","tag-landtagswahl-2027","tag-ub-delegiertenkonferenz","tag-ub-parteitag","tag-unterbezirks-delegiertenkonferenz","tag-wahlkreis-delegiertenkonferenz","tag-wahlkreiskonferenz","quellen-spd-unterbezirk-oberhausen"],"_links":{"self":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts\/13584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/comments?post=13584"}],"version-history":[{"count":0,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts\/13584\/revisions"}],"wp:attachment":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/media?parent=13584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/categories?post=13584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/tags?post=13584"},{"taxonomy":"quellen","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/quellen?post=13584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}