{"id":6041,"date":"2019-01-25T14:13:38","date_gmt":"2019-01-25T13:13:38","guid":{"rendered":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/?p=6041"},"modified":"2019-01-25T14:13:38","modified_gmt":"2019-01-25T13:13:38","slug":"baumassnahme-gut-begleiten","status":"publish","type":"post","link":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/2019\/01\/25\/baumassnahme-gut-begleiten\/","title":{"rendered":"Bauma\u00dfnahme gut begleiten"},"content":{"rendered":"<div id=\"attachment_1481\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/krey_thomas_14.jpg\"><img aria-describedby=\"caption-attachment-1481\" decoding=\"async\" class=\"size-full wp-image-1481\" src=\"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-content\/uploads\/krey_thomas_14.jpg\" alt=\"\" width=\"140\" height=\"169\" \/><\/a><p id=\"caption-attachment-1481\" class=\"wp-caption-text\">Thomas Krey ist Mitglied des Rates der Stadt und Bezirksb\u00fcrgermeister von Osterfeld<\/p><\/div>\n<p>Erfreut hat Osterfelds Bezirksb\u00fcrgermeister Thomas Krey (SPD) die Nachricht aufgenommen, dass die Gleisunterf\u00fchrung an der Osterfelder Stra\u00dfe verbreitert werden soll, so dass dann drei Fahrstreifen f\u00fcr Autos, zwei Radwege und zwei B\u00fcrgersteige zur Verf\u00fcgung stehen werden. &#8222;Dieses Nadel\u00f6hr zu verbreitern, ist auf jeden Fall ein Gewinn f\u00fcr die Osterfelder B\u00fcrgerinnen und B\u00fcrger, f\u00fcr den wir uns schon lange eingesetzt haben&#8220;, so Thomas Krey.<!--more--><\/p>\n<p>&#8222;Eine gro\u00dfe Entlastung f\u00fcr den Verkehr rund ums Centro sollte man sich von dieser einzelnen Ma\u00dfnahme allerdings nicht erwarten&#8220;, so der Bezirksb\u00fcrgermeister, der zudem fordert, sich rechtzeitig Gedanken \u00fcber die Verkehrsf\u00fchrung w\u00e4hrend der Bauarbeiten zu machen.<\/p>\n<p>&#8222;So wichtig diese Ma\u00dfnahme ist, so klar ist auch, dass der Verkehr w\u00e4hrend der Bauarbeiten massiv beeintr\u00e4chtigt werden wird. In dieser Zeit brauchen wir tragf\u00e4hige Alternativen f\u00fcr Fu\u00dfg\u00e4nger, Radfahrer und den motorisierten Verkehr&#8220;, erwartet Thomas Krey.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfreut hat Osterfelds Bezirksb\u00fcrgermeister Thomas Krey (SPD) die Nachricht aufgenommen, dass die Gleisunterf\u00fchrung an der Osterfelder Stra\u00dfe verbreitert werden soll, so dass dann drei Fahrstreifen f\u00fcr Autos, zwei Radwege und&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[1813,41,1812,1814],"quellen":[326],"class_list":["post-6041","post","type-post","status-publish","format-standard","hentry","category-planen-bauen-wohnen-verkehr","tag-gleisunterfuehrung-osterfelder-strasse","tag-osterfeld","tag-osterfelder-strasse","tag-verkehrsfuehrung","quellen-spd-fraktion-oberhausen"],"_links":{"self":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts\/6041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/comments?post=6041"}],"version-history":[{"count":0,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts\/6041\/revisions"}],"wp:attachment":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/media?parent=6041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/categories?post=6041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/tags?post=6041"},{"taxonomy":"quellen","embeddable":true,"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/quellen?post=6041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}