{"id":4811,"count":1,"description":"","link":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/stichwort\/muttertag\/","name":"Muttertag","slug":"muttertag","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/tags\/4811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/posts?tags=4811"},{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/ajde_events?tags=4811"},{"href":"https:\/\/meier-gerdingh.de\/wp-spd-ob\/wp-json\/wp\/v2\/spd-frak-ob-antrag?tags=4811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}